{"id":1025,"date":"2019-08-27T08:48:20","date_gmt":"2019-08-27T08:48:20","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=2309"},"modified":"2022-05-27T05:54:39","modified_gmt":"2022-05-27T05:54:39","slug":"abogados-proponen-modificar-la-sic","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/","title":{"rendered":"Abogados proponen modificar la SIC"},"content":{"rendered":"<p>Especialistas preparan la propuesta y creen que la entidad tendr\u00eda que dejar algunos campos de acci\u00f3n.<\/p>\n<p>Al cumplirse diez a\u00f1os de aplicaci\u00f3n del r\u00e9gimen de la Libre Competencia en el pa\u00eds, un grupo de abogados prepara la propuesta de reforma y modernizaci\u00f3n al mismo. Los autores hablaron para <strong><a href=\"https:\/\/www.asuntoslegales.com.co\/actualidad\/como-proponen-que-cambie-la-superintendencia-de-industria-2900026\" target=\"_blank\" rel=\"noopener\">Asuntos Legales<\/a><\/strong> sobre su propuesta.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2319 size-full\" src=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/abogados_sic.jpg\" alt=\"\" width=\"817\" height=\"614\" \/><\/p>\n<p><strong>\u00bfPor qu\u00e9 reformar el r\u00e9gimen de libre competencia?<\/strong><\/p>\n<p>Todo esquema de libre competencia tiene su ciclo y lleg\u00f3 la hora de comenzar a hacer algunos ajustes a las normas de procedimiento en Colombia para garantizar el debido proceso y la eficacia. La idea no es impedir la aplicaci\u00f3n del derecho de la competencia. Estamos convencidos que este principio es fundamental y genera competitividad en el pa\u00eds.<\/p>\n<p><strong>\u00bfC\u00f3mo modificar las investigaciones?<\/strong><\/p>\n<p>La idea es que los tiempos de las investigaciones, en especial para las personas naturales, sea claro porque hoy la Superintendencia hace visitas en etapa preliminar, las personas sienten que est\u00e1n siendo investigadas y duran a\u00f1os sin saber claramente si est\u00e1n siendo o no investigados.<br \/>\nAdem\u00e1s es muy importante que no sea la misma persona que acusa, la que define.<\/p>\n<p><strong>En la etapa preliminar \u00bfQu\u00e9 garant\u00edas debe haber?<\/strong><\/p>\n<p>En el mundo est\u00e1n prohibidas las expediciones de pesca y la sentencia de la Corte Constitucional de 2019 es totalmente clara en que la autoridad no necesita orden judicial para hacer las visitas, pero s\u00ed informar y determinar qu\u00e9 est\u00e1 averiguando y cu\u00e1les son los hechos para que la persona pueda declarar sobre ello y no sobre otras cosas. Los documentos recaudados deben estar relacionados con ese hecho.<\/p>\n<p><strong>\u00bfEst\u00e1n de acuerdo con aumentar las multas?<\/strong><\/p>\n<p>Las multas son una parte de los instrumentos de la autoridad, pero hay que ir m\u00e1s all\u00e1. En este momento el problema es que entre cero y 100.000 salarios m\u00ednimos de multa, no hay previsibilidad y la diferencia de casos a veces no se identifica. Es una regla b\u00e1sica de un Estado de derecho, con rigor pero previsibilidad. Aqu\u00ed no es costumbre hacer seguimiento y determinar la efectividad de las multas, no es posible debatir su valor si no sabemos realmente si est\u00e1n funcionando.<\/p>\n<p><strong>\u00bfC\u00f3mo m\u00e1s podr\u00edan pagar las empresas?<\/strong><\/p>\n<p>Hoy el sistema no tiene ninguna relaci\u00f3n entre las actividades de la Superindustria y la reparaci\u00f3n social. Se puede recaudar mucho dinero pero el impacto en el mercado no se conoce. La pol\u00edtica tambi\u00e9n deber\u00eda estar dirigida a restaurar el da\u00f1o a los consumidores.<\/p>\n<p><strong>\u00bfQu\u00e9 m\u00e1s deber\u00eda modificar la reforma?<\/strong><\/p>\n<p>La arquitectura de la autoridad de competencia, ser\u00eda mucho m\u00e1s conveniente que sea colegiada e independiente del Gobierno. Tambi\u00e9n es necesaria una separaci\u00f3n entre quien investiga y quien sanciona. La Superintendencia debe ser especializada porque hoy tiene muchas funciones.<\/p>\n<p>Otro problema es que nuestro cat\u00e1logo de pr\u00e1cticas anticompetitivas es de 1992. Desde eso ha evolucionado la restricci\u00f3n de la competencia.<\/p>\n<p><strong>*Puedes leer tambi\u00e9n el art\u00edculo original en <a href=\"https:\/\/www.asuntoslegales.com.co\/actualidad\/como-proponen-que-cambie-la-superintendencia-de-industria-2900026\" target=\"_blank\" rel=\"noopener\">Asuntos Legales.<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Especialistas preparan la propuesta y creen que la entidad tendr\u00eda que dejar algunos campos de acci\u00f3n. Al cumplirse diez&#8230;<\/p>","protected":false},"author":1,"featured_media":1027,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15],"tags":[51],"class_list":["post-1025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-la-republica","tag-asuntos-legales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abogados proponen modificar la SIC - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abogados proponen modificar la SIC - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Especialistas preparan la propuesta y creen que la entidad tendr\u00eda que dejar algunos campos de acci\u00f3n. Al cumplirse diez...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-27T08:48:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T05:54:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/abogados_240.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"Abogados proponen modificar la SIC\",\"datePublished\":\"2019-08-27T08:48:20+00:00\",\"dateModified\":\"2022-05-27T05:54:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/\"},\"wordCount\":520,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/abogados_240.jpg\",\"keywords\":[\"Asuntos Legales\"],\"articleSection\":[\"Diario La Rep\u00fablica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/\",\"name\":\"Abogados proponen modificar la SIC - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/abogados_240.jpg\",\"datePublished\":\"2019-08-27T08:48:20+00:00\",\"dateModified\":\"2022-05-27T05:54:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/abogados_240.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/abogados_240.jpg\",\"width\":240,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/08\\\/27\\\/abogados-proponen-modificar-la-sic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abogados proponen modificar la SIC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abogados proponen modificar la SIC - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/","og_locale":"en_US","og_type":"article","og_title":"Abogados proponen modificar la SIC - Archila Abogados","og_description":"Especialistas preparan la propuesta y creen que la entidad tendr\u00eda que dejar algunos campos de acci\u00f3n. Al cumplirse diez...","og_url":"https:\/\/archilaabogados.com\/en\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/","og_site_name":"Archila Abogados","article_published_time":"2019-08-27T08:48:20+00:00","article_modified_time":"2022-05-27T05:54:39+00:00","og_image":[{"width":240,"height":290,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/abogados_240.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"Abogados proponen modificar la SIC","datePublished":"2019-08-27T08:48:20+00:00","dateModified":"2022-05-27T05:54:39+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/"},"wordCount":520,"image":{"@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/abogados_240.jpg","keywords":["Asuntos Legales"],"articleSection":["Diario La Rep\u00fablica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/","url":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/","name":"Abogados proponen modificar la SIC - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/abogados_240.jpg","datePublished":"2019-08-27T08:48:20+00:00","dateModified":"2022-05-27T05:54:39+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/abogados_240.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/abogados_240.jpg","width":240,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2019\/08\/27\/abogados-proponen-modificar-la-sic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"Abogados proponen modificar la SIC"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=1025"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1025\/revisions"}],"predecessor-version":[{"id":1591,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1025\/revisions\/1591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/1027"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=1025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=1025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}