{"id":1051,"date":"2019-05-07T23:28:52","date_gmt":"2019-05-07T23:28:52","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=1973"},"modified":"2022-05-27T03:57:11","modified_gmt":"2022-05-27T03:57:11","slug":"se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/","title":{"rendered":"Se cumpli\u00f3 conferencia &#8216;Derechos Fundamentales y Protecci\u00f3n al Consumidor&#8217;"},"content":{"rendered":"<p><strong>Universidad Externado de Colombia.<\/strong><\/p>\n<p><strong>Conferencistas:<\/strong><br \/>\nDionisio de la Cruz Camargo<br \/>\nDocente Derecho Econ\u00f3mico y abogado consultor.<\/p>\n<p>Mar\u00eda Carolina Corcione Morales<br \/>\nSuperintendente delegada para la protecci\u00f3n al consumidor.<\/p>\n<p>El conferencista analiz\u00f3 los fundamentos y bases de la Resoluci\u00f3n 92526 de 2018 de la Superintendencia de Industria y Comercio, por la cual se imparti\u00f3 una orden administrativa en materia de protecci\u00f3n al consumidor, y en particular, tres temas: la constitucionalizaci\u00f3n del derecho del consumo; si la informaci\u00f3n y la publicidad son derechos derivados de la libertad de expresi\u00f3n o hace parte de los ejercicios econ\u00f3micos; y la responsabilidad de la cadena publicitaria, a prop\u00f3sito de la responsabilidad en cabeza de los medios de comunicaci\u00f3n.<\/p>\n<p><strong><a href=\"https:\/\/bit.ly\/2VOh0yk\" target=\"_blank\" rel=\"noopener\">Clic ac\u00e1 para ver conferencia<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Universidad Externado de Colombia. Conferencistas: Dionisio de la Cruz Camargo Docente Derecho Econ\u00f3mico y abogado consultor. Mar\u00eda Carolina Corcione&#8230;<\/p>","protected":false},"author":1,"featured_media":1004,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[20],"tags":[52],"class_list":["post-1051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seminarios-y-talleres","tag-foros-seminarios-y-talleres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se cumpli\u00f3 conferencia &#039;Derechos Fundamentales y Protecci\u00f3n al Consumidor&#039; - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se cumpli\u00f3 conferencia &#039;Derechos Fundamentales y Protecci\u00f3n al Consumidor&#039; - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Universidad Externado de Colombia. Conferencistas: Dionisio de la Cruz Camargo Docente Derecho Econ\u00f3mico y abogado consultor. Mar\u00eda Carolina Corcione...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-07T23:28:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T03:57:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/balance_240.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"Se cumpli\u00f3 conferencia &#8216;Derechos Fundamentales y Protecci\u00f3n al Consumidor&#8217;\",\"datePublished\":\"2019-05-07T23:28:52+00:00\",\"dateModified\":\"2022-05-27T03:57:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/\"},\"wordCount\":137,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/balance_240.jpg\",\"keywords\":[\"Foros - Seminarios - Talleres\"],\"articleSection\":[\"Seminarios y Talleres\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/\",\"name\":\"Se cumpli\u00f3 conferencia 'Derechos Fundamentales y Protecci\u00f3n al Consumidor' - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/balance_240.jpg\",\"datePublished\":\"2019-05-07T23:28:52+00:00\",\"dateModified\":\"2022-05-27T03:57:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/balance_240.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/balance_240.jpg\",\"width\":240,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2019\\\/05\\\/07\\\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se cumpli\u00f3 conferencia &#8216;Derechos Fundamentales y Protecci\u00f3n al Consumidor&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se cumpli\u00f3 conferencia 'Derechos Fundamentales y Protecci\u00f3n al Consumidor' - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/","og_locale":"en_US","og_type":"article","og_title":"Se cumpli\u00f3 conferencia 'Derechos Fundamentales y Protecci\u00f3n al Consumidor' - Archila Abogados","og_description":"Universidad Externado de Colombia. Conferencistas: Dionisio de la Cruz Camargo Docente Derecho Econ\u00f3mico y abogado consultor. Mar\u00eda Carolina Corcione...","og_url":"https:\/\/archilaabogados.com\/en\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/","og_site_name":"Archila Abogados","article_published_time":"2019-05-07T23:28:52+00:00","article_modified_time":"2022-05-27T03:57:11+00:00","og_image":[{"width":240,"height":290,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/balance_240.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"Se cumpli\u00f3 conferencia &#8216;Derechos Fundamentales y Protecci\u00f3n al Consumidor&#8217;","datePublished":"2019-05-07T23:28:52+00:00","dateModified":"2022-05-27T03:57:11+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/"},"wordCount":137,"image":{"@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/balance_240.jpg","keywords":["Foros - Seminarios - Talleres"],"articleSection":["Seminarios y Talleres"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/","url":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/","name":"Se cumpli\u00f3 conferencia 'Derechos Fundamentales y Protecci\u00f3n al Consumidor' - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/balance_240.jpg","datePublished":"2019-05-07T23:28:52+00:00","dateModified":"2022-05-27T03:57:11+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/balance_240.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/balance_240.jpg","width":240,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2019\/05\/07\/se-cumplio-conferencia-derechos-fundamentales-y-proteccion-al-consumidor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"Se cumpli\u00f3 conferencia &#8216;Derechos Fundamentales y Protecci\u00f3n al Consumidor&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=1051"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1051\/revisions"}],"predecessor-version":[{"id":1605,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1051\/revisions\/1605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/1004"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=1051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=1051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}