{"id":1345,"date":"2017-12-17T10:14:34","date_gmt":"2017-12-17T10:14:34","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=739"},"modified":"2022-06-07T19:25:30","modified_gmt":"2022-06-07T19:25:30","slug":"por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/","title":{"rendered":"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico?"},"content":{"rendered":"<p>Las coyunturas y esc\u00e1ndalos en la Honorable Corte Constitucional han generado una serie de arreglos institucionales que, con buen \u00e1nimo, apuntan hacia una corporaci\u00f3n con mayor transparencia en todos sus procedimientos. Uno de esos es el que involucra la selecci\u00f3n de tutelas para revisi\u00f3n.<\/p>\n<p>Al respecto, se expidi\u00f3 el acuerdo 01 del 30 de abril de 2015, el cual modifica el reglamento interno de la Corte Constitucional. En \u00e9ste, se cre\u00f3 la Unidad de An\u00e1lisis y Seguimiento al Proceso de Selecci\u00f3n de Tutelas, que, seg\u00fan el art\u00edculo 49 A deber\u00e1 guiarse por los criterios objetivos, subjetivos y complementarios indicados en la norma mencionada, y en adici\u00f3n deber\u00e1 tener en cuenta la relevancia constitucional del asunto, particularmente trat\u00e1ndose de casos de contenido econ\u00f3mico.<\/p>\n<p>Este aspecto llama la atenci\u00f3n, por tratarse de una discriminaci\u00f3n de casos, ordenando una mayor severidad para la selecci\u00f3n de aquellos que tengan \u201ccontenido econ\u00f3mico\u201d. Es mi opini\u00f3n que esa redacci\u00f3n no es auto-explicativa y a\u00fan m\u00e1s, puede ser inconstitucional:<\/p>\n<p><strong>1. Es una violaci\u00f3n al derecho a la igualdad<\/strong><\/p>\n<p>Primero, vale preguntarse c\u00f3mo aplicar\u00eda este criterio seg\u00fan el demandante: \u00bfes lo mismo un caso de contenido econ\u00f3mico para un \u201cpobre\u201d que para un \u201crico\u201d? Estar\u00eda tentado a decir que no, y que la Unidad de Selecci\u00f3n de Tutelas seleccionar\u00eda una tutela de un \u201cpobre\u201d justificado en que se vulneran sus condiciones a vivir dignamente, aunque ambos tengan contenido econ\u00f3mico.<\/p>\n<p>Entonces, los casos que no tendr\u00e1n acceso a la revisi\u00f3n de la Corte son los de contenido econ\u00f3mico de los \u201cricos\u201d. Al respecto, surge otra pregunta: \u00bfseleccionar\u00eda la Unidad un pleito puramente contractual, en el que se debata la causal de cancelaci\u00f3n de una cuenta corriente? Seg\u00fan el criterio en menci\u00f3n la Unidad no lo seleccionar\u00eda, pues ser\u00eda un pleito entre una persona con cuenta corriente (quien probablemente no encaja en la categor\u00eda de \u201cpobre\u201d) sobre un tema eminentemente contractual y de contenido econ\u00f3mico (terminaci\u00f3n de un contrato financiero).<\/p>\n<p>No obstante, hasta el d\u00eda de hoy la Corte ha seleccionado al menos cinco casos en los que se debate la cancelaci\u00f3n de una cuenta corriente, justificado en la relevancia constitucional del \u201cderecho al reconocimiento de la personalidad jur\u00eddica como una verdadera garant\u00eda de la persona natural para que goce de la capacidad jur\u00eddica o de la aptitud para ser titular de derechos y obligaciones, no s\u00f3lo de contenido extrapatrimonial sino tambi\u00e9n de car\u00e1cter econ\u00f3mico\u201d.<\/p>\n<p>Desde esta perspectiva, los \u201cricos\u201d tienen derecho a que la Corte revise pleitos contractuales y econ\u00f3micos, sin que sean desechados de entrada por la Unidad de Selecci\u00f3n.<\/p>\n<p><strong>2. Relevancia constitucional de proteger el patrimonio y la propiedad<\/strong><\/p>\n<p>Congruente con lo anterior, imponer un filtro para los pleitos \u201cde contenido econ\u00f3mico\u201d no s\u00f3lo es artificial, sino inconstitucional porque desconoce la relevancia constitucional del patrimonio y la propiedad:<\/p>\n<p>Es artificial, porque todos los pleitos tienen un contenido econ\u00f3mico: Todos los derechos cuestan y la implementaci\u00f3n pr\u00e1ctica de los derechos exigir\u00e1 una erogaci\u00f3n a cargo del Estado o de un particular -seg\u00fan el caso-, otorg\u00e1ndole a la generalidad de conflictos un contenido econ\u00f3mico.<\/p>\n<p>Y es inconstitucional, porque en nuestro pa\u00eds hay un abanico de sentencias de tutela en las cuales se describe la relevancia constitucional de proteger el patrimonio de las personas. Entre otras, la Corte Constitucional ha fallado tutelas del siguiente orden:<\/p>\n<p>(i) El Ministerio P\u00fablico e incluso los jueces de tutela est\u00e1n legitimados y deben usar la tutela para proteger el patrimonio p\u00fablico.<\/p>\n<p>(ii) Respecto de la protecci\u00f3n del patrimonio privado, se ha concedido amparo bajo la premisa que la propiedad privada es protegible, cuando su vulneraci\u00f3n tenga alguna relaci\u00f3n con la dignidad humana.<\/p>\n<p>Pero, en la jurisprudencia reciente se ha superado esa limitaci\u00f3n de exigir una conexidad con la dignidad humana, pues \u201c[e]sa relaci\u00f3n entre todos los derechos, y entre estos y la dignidad humana se manifiesta en los principios de interdependencia e indivisibilidad de los derechos humanos, y demuestra c\u00f3mo puede resultar superfluo hablar de conexidad en un escenario en que existe una conexi\u00f3n estrecha entre todos ellos\u201d.<\/p>\n<p>(iii) El patrimonio es un atributo de la personalidad de car\u00e1cter inalienable, irrenunciable, vitalicio y personal, inherente al ser humano, y tambi\u00e9n es un atributo de la personalidad de las sociedades. La Corte ha reconocido que el patrimonio le permite a las sociedades mercantiles desempe\u00f1arse en la vida jur\u00eddica, por lo cual la perturbaci\u00f3n de este atributo afecta su derecho a la personalidad.<\/p>\n<p>(iv) Tambi\u00e9n se han revisado decisiones estrictamente contractuales, incluyendo la imposici\u00f3n de penalidades entre particulares y la negativa a contratar.<\/p>\n<p>Sobre lo anterior, los derechos econ\u00f3micos se gu\u00edan bajo el principio de progresividad. En virtud de este principio, el sistema debe apuntar hacia el desarrollo y expansi\u00f3n de cada derecho (incluidos los econ\u00f3micos), para lo cual la jurisprudencia constitucional juega un rol indispensable.<\/p>\n<p>Pero, con este filtro, se est\u00e1 cortando de tajo, la posibilidad de que haya posteriores desarrollos en la Corte sobre el contenido de los derechos econ\u00f3micos, lo cual desconoce varios tratados internacionales, y es grave para el pa\u00eds y sus habitantes porque no se reconocer\u00e1n nuevas realidades que surjan en el futuro, a falta de un juez constitucional que se pronuncie al respecto.<\/p>\n<p><strong>3. La Unidad har\u00e1 una ponderaci\u00f3n de derechos<\/strong><\/p>\n<p>Si todo lo anterior no fuera suficientemente grave, la tarea de la Unidad de Selecci\u00f3n con ese criterio es determinar cu\u00e1les son los bienes en conflicto (para decidir si es un pleito econ\u00f3mico) y asignarle un peso abstracto a los mismos.<\/p>\n<p>Pero esa es una tarea de la Corte para cada caso concreto: No es pac\u00edfico en todos los casos determinar cu\u00e1les son los bienes jur\u00eddicos y, por ejemplo, en un caso para una persona puede estar involucrado el derecho a competir en el mercado (contenido econ\u00f3mico), mientras que para otra puede ser el derecho a trabajar.<\/p>\n<p>Esta no es una tarea para la Unidad, sino para los Magistrados.<\/p>\n<p><strong>4. Entonces, \u00bfhacia d\u00f3nde apunta el criterio del reglamento?<\/strong><\/p>\n<p>Como ya se expuso, (i) todos los derechos tienen un contenido econ\u00f3mico y un costo para el obligado de garantizar el derecho; (ii) todos los derechos tienen una conexi\u00f3n con la dignidad humana y los otros derechos constitucionales; y (iii) por eso el patrimonio p\u00fablico y privado, la propiedad privada, el derecho a contratar e incluso el derecho a competir -cuya base es la igualdad- han sido protegidos por v\u00eda de la acci\u00f3n de tutela.<\/p>\n<p>Esa mayor severidad ordenada en el reglamento para que la Unidad no seleccione tutelas de contenido econ\u00f3mico es un criterio artificial, no acorde con nuestro sistema, y que estar\u00eda dejando por fuera asuntos que son relevantes constitucionalmente.<\/p>\n<p>A ese respecto, por ahora una soluci\u00f3n formal: Para incrementar la probabilidad de selecci\u00f3n de una tutela, las pretensiones de la demanda y el problema jur\u00eddico planteado por el actor no podr\u00edan estar formulados como una reclamaci\u00f3n de una suma de dinero, as\u00ed la consecuencia del proceso sea la restituci\u00f3n o pago de dinero en favor del actor por violaci\u00f3n de sus derechos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las coyunturas y esc\u00e1ndalos en la Honorable Corte Constitucional han generado una serie de arreglos institucionales que, con buen&#8230;<\/p>","protected":false},"author":1,"featured_media":1335,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[26],"tags":[51],"class_list":["post-1345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-de-dinero","tag-asuntos-legales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico? - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico? - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Las coyunturas y esc\u00e1ndalos en la Honorable Corte Constitucional han generado una serie de arreglos institucionales que, con buen...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-17T10:14:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-07T19:25:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/mercado_de_dinero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico?\",\"datePublished\":\"2017-12-17T10:14:34+00:00\",\"dateModified\":\"2022-06-07T19:25:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/\"},\"wordCount\":1268,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/mercado_de_dinero.jpg\",\"keywords\":[\"Asuntos Legales\"],\"articleSection\":[\"Mercado de Dinero\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/\",\"name\":\"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico? - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/mercado_de_dinero.jpg\",\"datePublished\":\"2017-12-17T10:14:34+00:00\",\"dateModified\":\"2022-06-07T19:25:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/mercado_de_dinero.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/mercado_de_dinero.jpg\",\"width\":240,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/17\\\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico? - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/","og_locale":"en_US","og_type":"article","og_title":"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico? - Archila Abogados","og_description":"Las coyunturas y esc\u00e1ndalos en la Honorable Corte Constitucional han generado una serie de arreglos institucionales que, con buen...","og_url":"https:\/\/archilaabogados.com\/en\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/","og_site_name":"Archila Abogados","article_published_time":"2017-12-17T10:14:34+00:00","article_modified_time":"2022-06-07T19:25:30+00:00","og_image":[{"width":240,"height":290,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/mercado_de_dinero.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico?","datePublished":"2017-12-17T10:14:34+00:00","dateModified":"2022-06-07T19:25:30+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/"},"wordCount":1268,"image":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/mercado_de_dinero.jpg","keywords":["Asuntos Legales"],"articleSection":["Mercado de Dinero"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/","url":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/","name":"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico? - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/mercado_de_dinero.jpg","datePublished":"2017-12-17T10:14:34+00:00","dateModified":"2022-06-07T19:25:30+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/mercado_de_dinero.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/mercado_de_dinero.jpg","width":240,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2017\/12\/17\/por-que-no-seleccionaran-las-tutelas-de-casos-de-contenido-economico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 no seleccionar\u00e1n las tutelas de casos de contenido econ\u00f3mico?"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=1345"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1345\/revisions"}],"predecessor-version":[{"id":1754,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1345\/revisions\/1754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/1335"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=1345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=1345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=1345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}