{"id":1402,"date":"2017-12-15T09:51:46","date_gmt":"2017-12-15T09:51:46","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=615"},"modified":"2022-05-27T03:44:08","modified_gmt":"2022-05-27T03:44:08","slug":"un-holding-estatal-para-controlar-las-inversiones-publicas","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/","title":{"rendered":"Un &#8216;holding estatal&#8217; para controlar las inversiones p\u00fablicas"},"content":{"rendered":"<p>Editorial elaborada y redactada por el Dr. Emilio Jos\u00e9 Archila en marzo de 2012 para la Revista Contexto de la Universidad Externado de Colombia. A continuaci\u00f3n puedes leer la misma <a href=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/contexto-36.pdf\" target=\"_blank\" rel=\"noopener\"><strong>dando clic aqu\u00ed.<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Editorial elaborada y redactada por el Dr. Emilio Jos\u00e9 Archila en marzo de 2012 para la Revista Contexto de&#8230;<\/p>","protected":false},"author":1,"featured_media":1176,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[24],"tags":[51],"class_list":["post-1402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contexto","tag-asuntos-legales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un &#039;holding estatal&#039; para controlar las inversiones p\u00fablicas - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un &#039;holding estatal&#039; para controlar las inversiones p\u00fablicas - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Editorial elaborada y redactada por el Dr. Emilio Jos\u00e9 Archila en marzo de 2012 para la Revista Contexto de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-15T09:51:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T03:44:08+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/universidad_externado_colombia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"Un &#8216;holding estatal&#8217; para controlar las inversiones p\u00fablicas\",\"datePublished\":\"2017-12-15T09:51:46+00:00\",\"dateModified\":\"2022-05-27T03:44:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/\"},\"wordCount\":43,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/universidad_externado_colombia.jpg\",\"keywords\":[\"Asuntos Legales\"],\"articleSection\":[\"Contexto\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/\",\"name\":\"Un 'holding estatal' para controlar las inversiones p\u00fablicas - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/universidad_externado_colombia.jpg\",\"datePublished\":\"2017-12-15T09:51:46+00:00\",\"dateModified\":\"2022-05-27T03:44:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/universidad_externado_colombia.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/universidad_externado_colombia.jpg\",\"width\":240,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2017\\\/12\\\/15\\\/un-holding-estatal-para-controlar-las-inversiones-publicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un &#8216;holding estatal&#8217; para controlar las inversiones p\u00fablicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un 'holding estatal' para controlar las inversiones p\u00fablicas - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/","og_locale":"en_US","og_type":"article","og_title":"Un 'holding estatal' para controlar las inversiones p\u00fablicas - Archila Abogados","og_description":"Editorial elaborada y redactada por el Dr. Emilio Jos\u00e9 Archila en marzo de 2012 para la Revista Contexto de...","og_url":"https:\/\/archilaabogados.com\/en\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/","og_site_name":"Archila Abogados","article_published_time":"2017-12-15T09:51:46+00:00","article_modified_time":"2022-05-27T03:44:08+00:00","og_image":[{"width":240,"height":290,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/universidad_externado_colombia.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"Un &#8216;holding estatal&#8217; para controlar las inversiones p\u00fablicas","datePublished":"2017-12-15T09:51:46+00:00","dateModified":"2022-05-27T03:44:08+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/"},"wordCount":43,"image":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/universidad_externado_colombia.jpg","keywords":["Asuntos Legales"],"articleSection":["Contexto"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/","url":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/","name":"Un 'holding estatal' para controlar las inversiones p\u00fablicas - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/universidad_externado_colombia.jpg","datePublished":"2017-12-15T09:51:46+00:00","dateModified":"2022-05-27T03:44:08+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/universidad_externado_colombia.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2017\/12\/universidad_externado_colombia.jpg","width":240,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2017\/12\/15\/un-holding-estatal-para-controlar-las-inversiones-publicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"Un &#8216;holding estatal&#8217; para controlar las inversiones p\u00fablicas"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=1402"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1402\/revisions"}],"predecessor-version":[{"id":1786,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/1402\/revisions\/1786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/1176"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=1402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=1402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=1402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}