{"id":958,"date":"2021-01-29T07:59:35","date_gmt":"2021-01-29T07:59:35","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=2868"},"modified":"2022-05-27T05:54:16","modified_gmt":"2022-05-27T05:54:16","slug":"a-regular-sin-populismo","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2021\/01\/29\/a-regular-sin-populismo\/","title":{"rendered":"A regular sin populismo"},"content":{"rendered":"<p><strong>Opini\u00f3n de Dionisio de la Cruz Camargo para Asuntos Legales. 28 de enero de 2021.<\/strong><\/p>\n<p>La regulaci\u00f3n econ\u00f3mica y la libre competencia son dos herramientas de pol\u00edtica econ\u00f3mica que generalmente son resistidas, a pesar de los beneficios que traen para el mercado, a no ser que suceda algo particularmente tr\u00e1gico o impactante que concientice a la sociedad de su necesidad, como dos asuntos que han sacudido al mundo en este principio de a\u00f1o.<\/p>\n<p>Me refiero a la decisi\u00f3n de Twiter, Facebook e Instagram de bloquear al expresidente Donald Trump. Los hechos acaecidos el 6 de enero pasado que nos dejaron at\u00f3nitos, a los ojos de todos fueron originados e instigados por el saliente Presidente de los Estados Unidos y fue la gota que determin\u00f3 la decisi\u00f3n de esos gigantes tecnol\u00f3gicos de bloquear permanentemente las cuentas de quien sin duda era una de las grandes figuras de las redes, cuyos seguidores se contaban por varias decenas de millones en todo el mundo. Al aplauso inicial de la mayor\u00eda, surgi\u00f3 la preocupaci\u00f3n. \u00bfDeber\u00edan tener estas redes el poder unilateral de vetar a alguien por sus opiniones, por muy odiosas o mentirosas que sean, incluso si incitan al desconocimiento del estado de derecho?.<\/p>\n<p>Acto seguido, tanto el Ex Presidente Trump como su red de seguidores han migrado a otras redes sociales, que aparentemente han respetado su derecho a la libre expresi\u00f3n.<\/p>\n<p>Por otro lado, WhatsApp, la aplicaci\u00f3n m\u00e1s popular en comunicaciones de texto y audio, se ha visto en calzas prietas luego que inform\u00f3 a todos sus usuarios de un cambio en sus pol\u00edticas de protecci\u00f3n de datos, que en pocas palabras, le permit\u00eda a la aplicaci\u00f3n compartir los datos de quienes la hubieren bajado, con Facebook, empresa que es su propietaria. Esta informaci\u00f3n origin\u00f3 el terror en muchos de sus usuarios, quienes consideran que esa variaci\u00f3n en las pol\u00edticas implicaba compartir, incluso, el contenido de las conversaciones. La aplicaci\u00f3n reaccion\u00f3 luego de la avalancha de retiros de la aplicaci\u00f3n y el incremento de la adquisici\u00f3n de aplicaciones rivales por parte de los usuarios, gritando a los cuatro vientos que no, que el cambio de pol\u00edticas no implicaba que pudiera tener acceso a las conversaciones ya que estas estaban encriptadas de \u201cpunta a punta\u201d.<\/p>\n<p>Estos eventos han servido para dar un respaldo general a las autoridades de todo el mundo que hab\u00edan venido trabajando en regular a estos gigantes, pero que no contaban con el apoyo de esos cientos de millones de usuarios que felices utilizamos las redes sin darnos cuenta del poder que tienen frente al manejo de la informaci\u00f3n y de nuestras vidas. As\u00ed mismo, han evidenciado la importancia de la competencia como factor que equilibra el mercado. Sin aplicaciones que compitan con WhatsApp, los usuarios no hubieran tenido opciones y esta aplicaci\u00f3n no hubiera reaccionado saliendo a dar largas explicaciones y a pensarlo dos veces antes de imponer condiciones. Ahora, corresponde a los Estados regular sin el populismo de los acontecimientos y sin sacrificar la libre competencia.<\/p>\n<p><strong>Tambi\u00e9n puedes leer esta columna de opini\u00f3n en el portal Asuntos Legales. <a href=\"https:\/\/www.asuntoslegales.com.co\/analisis\/dionisio-de-la-cruz-camargo-2765738\/a-regular-sin-populismo-3117067\" target=\"_blank\" rel=\"noopener\">Clic ac\u00e1.<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Opini\u00f3n de Dionisio de la Cruz Camargo para Asuntos Legales. 28 de enero de 2021. La regulaci\u00f3n econ\u00f3mica y&#8230;<\/p>","protected":false},"author":1,"featured_media":887,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15],"tags":[51],"class_list":["post-958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-la-republica","tag-asuntos-legales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A regular sin populismo - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2021\/01\/29\/a-regular-sin-populismo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A regular sin populismo - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Opini\u00f3n de Dionisio de la Cruz Camargo para Asuntos Legales. 28 de enero de 2021. La regulaci\u00f3n econ\u00f3mica y...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2021\/01\/29\/a-regular-sin-populismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-29T07:59:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T05:54:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/dionisio_asuntos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"A regular sin populismo\",\"datePublished\":\"2021-01-29T07:59:35+00:00\",\"dateModified\":\"2022-05-27T05:54:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/\"},\"wordCount\":545,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/dionisio_asuntos.jpg\",\"keywords\":[\"Asuntos Legales\"],\"articleSection\":[\"Diario La Rep\u00fablica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/\",\"name\":\"A regular sin populismo - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/dionisio_asuntos.jpg\",\"datePublished\":\"2021-01-29T07:59:35+00:00\",\"dateModified\":\"2022-05-27T05:54:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/dionisio_asuntos.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/dionisio_asuntos.jpg\",\"width\":240,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2021\\\/01\\\/29\\\/a-regular-sin-populismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A regular sin populismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A regular sin populismo - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2021\/01\/29\/a-regular-sin-populismo\/","og_locale":"en_US","og_type":"article","og_title":"A regular sin populismo - Archila Abogados","og_description":"Opini\u00f3n de Dionisio de la Cruz Camargo para Asuntos Legales. 28 de enero de 2021. La regulaci\u00f3n econ\u00f3mica y...","og_url":"https:\/\/archilaabogados.com\/en\/2021\/01\/29\/a-regular-sin-populismo\/","og_site_name":"Archila Abogados","article_published_time":"2021-01-29T07:59:35+00:00","article_modified_time":"2022-05-27T05:54:16+00:00","og_image":[{"width":240,"height":290,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/dionisio_asuntos.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"A regular sin populismo","datePublished":"2021-01-29T07:59:35+00:00","dateModified":"2022-05-27T05:54:16+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/"},"wordCount":545,"image":{"@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/dionisio_asuntos.jpg","keywords":["Asuntos Legales"],"articleSection":["Diario La Rep\u00fablica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/","url":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/","name":"A regular sin populismo - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/dionisio_asuntos.jpg","datePublished":"2021-01-29T07:59:35+00:00","dateModified":"2022-05-27T05:54:16+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/dionisio_asuntos.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/08\/dionisio_asuntos.jpg","width":240,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2021\/01\/29\/a-regular-sin-populismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"A regular sin populismo"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=958"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/958\/revisions"}],"predecessor-version":[{"id":1545,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/958\/revisions\/1545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/887"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}