{"id":964,"date":"2020-09-17T07:11:06","date_gmt":"2020-09-17T07:11:06","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=2801"},"modified":"2022-05-27T05:54:17","modified_gmt":"2022-05-27T05:54:17","slug":"no-es-el-momento-de-los-prejuicios-economicos","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/","title":{"rendered":"No es el momento de los prejuicios econ\u00f3micos"},"content":{"rendered":"<p><strong>Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Septiembre 16 de 2020.<\/strong><\/p>\n<p><strong>No es el momento de los prejuicios econ\u00f3micos<\/strong><\/p>\n<p>La historia se repite y parece que estuvi\u00e9ramos como cuando comenz\u00e1bamos a comprender lo bueno y lo malo de competir. El proceso natural que se desarroll\u00f3 con la posibilidad reconocida y protegida de acceder al mercado, y emprender cualquier actividad econ\u00f3mica, trajo consigo el surgimiento de grandes poderes econ\u00f3micos que llevaron a los legisladores de la \u00e9poca en los Estados Unidos a la expedici\u00f3n en el a\u00f1o 1890 de la Ley Sherman (Sherman Act), como respuesta al surgimiento de grandes capitales para tratar de impedir \u201cla monopolizaci\u00f3n o los intentos de monopolizaci\u00f3n\u201d.<\/p>\n<p>En declaraciones que se atribuyen al senador Sherman, sustent\u00f3 la norma explicando que \u201csi los poderes concentrados de estas combinaciones se otorgan a un solo hombre, es una prerrogativa regia e inconsistente con nuestra forma de Gobierno\u2026Si hay algo rechazable esto lo es. Si no soportamos un rey como poder pol\u00edtico, tampoco lo soportaremos sobre la producci\u00f3n, el transporte o cualquiera de las necesidades vitales. \u201d(Van Cise, Antitrust Past-present-Future, recogido por Herrero Su\u00e1rez, Carmen. 2006, Los Contratos Vinculados en el Derecho de la Competencia Madrid, Espa\u00f1a, Pag 83 Ed. La Ley).<\/p>\n<p>Y, fueron los jueces quienes desarrollaron tales deseos m\u00e1s que principios. El juez White en el ic\u00f3nico fallo contra la Est\u00e1ndar Oil Co, orden\u00f3 su fragmentaci\u00f3n por los m\u00e9todos que utilizaron sus due\u00f1os para lograr el control de varias industrias en aquel momento.<\/p>\n<p>Pero, hoy no estamos como los primeros legisladores y jueces. Ya tenemos un largo camino recorrido donde el capital privado ha sido el eje de desarrollo, de la mano de la innovaci\u00f3n y, sin dejar de lado el empuje del emprendimiento. Incluso, se ha reconocido la necesidad del capital privado como \u00fanico medio para la realizaci\u00f3n de ciertas actividades por la gran necesidad de capital o por la eficiencia que puede generar la iniciativa privada.<\/p>\n<p>Ahora bien, su innegable importancia en el desarrollo no implica que est\u00e9 exenta de control. Casi un siglo despu\u00e9s, Colombia le apost\u00f3, contrario a visi\u00f3n inicial norteamericana, a respaldar a aquellas empresas que contaran con una posici\u00f3n dominante, pero a castigar sus abusos y a impedir que, v\u00eda operaciones de integraciones econ\u00f3micas, pudieran restringir indebidamente la competencia.<\/p>\n<p>As\u00ed, hoy tampoco tenemos que comenzar de ceros. Si bien parece que la tecnolog\u00eda, que hoy apalanca a varias de las grandes empresas en el mundo, nos traslada a finales del siglo XIX bajo el desconcierto de enfrentar aparentes fen\u00f3menos desconocidos, lo cierto es que ya hemos recorrido bastante camino como para no caer en prejuicios econ\u00f3micos.<\/p>\n<p>La pandemia por la que seguimos navegando, ha mostrado la necesidad de contar un aparato productivo con la suficiente fortaleza como para absorber este tipo de embates. De hecho, la tarea es que el Estado apoye para que m\u00e1s sectores como el agr\u00edcola y el industrial puedan generar empresas fuertes que surjan y se mantengan, lo que seguramente va a requerir muchas reformas econ\u00f3micas estructurales entre otras a la ley de competencia, pero tambi\u00e9n a la tributaria y laboral.<\/p>\n<p><strong>Tambi\u00e9n puedes leer el art\u00edculo en el portal Asuntos Legales, dando <a href=\"https:\/\/www.asuntoslegales.com.co\/analisis\/dionisio-de-la-cruz-camargo-2765738\/no-es-el-momento-de-los-prejuicios-economicos-3060851\" target=\"_blank\" rel=\"noopener\">clic ac\u00e1.<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Septiembre 16 de 2020. No&#8230;<\/p>","protected":false},"author":1,"featured_media":868,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15],"tags":[51],"class_list":["post-964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-la-republica","tag-asuntos-legales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No es el momento de los prejuicios econ\u00f3micos - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No es el momento de los prejuicios econ\u00f3micos - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Septiembre 16 de 2020. No...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-17T07:11:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T05:54:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"No es el momento de los prejuicios econ\u00f3micos\",\"datePublished\":\"2020-09-17T07:11:06+00:00\",\"dateModified\":\"2022-05-27T05:54:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/\"},\"wordCount\":575,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"keywords\":[\"Asuntos Legales\"],\"articleSection\":[\"Diario La Rep\u00fablica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/\",\"name\":\"No es el momento de los prejuicios econ\u00f3micos - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"datePublished\":\"2020-09-17T07:11:06+00:00\",\"dateModified\":\"2022-05-27T05:54:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"width\":240,\"height\":304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/09\\\/17\\\/no-es-el-momento-de-los-prejuicios-economicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No es el momento de los prejuicios econ\u00f3micos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No es el momento de los prejuicios econ\u00f3micos - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/","og_locale":"en_US","og_type":"article","og_title":"No es el momento de los prejuicios econ\u00f3micos - Archila Abogados","og_description":"Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Septiembre 16 de 2020. No...","og_url":"https:\/\/archilaabogados.com\/en\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/","og_site_name":"Archila Abogados","article_published_time":"2020-09-17T07:11:06+00:00","article_modified_time":"2022-05-27T05:54:17+00:00","og_image":[{"width":240,"height":304,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"No es el momento de los prejuicios econ\u00f3micos","datePublished":"2020-09-17T07:11:06+00:00","dateModified":"2022-05-27T05:54:17+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/"},"wordCount":575,"image":{"@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","keywords":["Asuntos Legales"],"articleSection":["Diario La Rep\u00fablica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/","url":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/","name":"No es el momento de los prejuicios econ\u00f3micos - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","datePublished":"2020-09-17T07:11:06+00:00","dateModified":"2022-05-27T05:54:17+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","width":240,"height":304},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2020\/09\/17\/no-es-el-momento-de-los-prejuicios-economicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"No es el momento de los prejuicios econ\u00f3micos"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"predecessor-version":[{"id":1551,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/964\/revisions\/1551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/868"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}