{"id":972,"date":"2020-07-02T20:56:19","date_gmt":"2020-07-02T20:56:19","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=2769"},"modified":"2022-05-27T05:54:17","modified_gmt":"2022-05-27T05:54:17","slug":"despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/","title":{"rendered":"Despu\u00e9s del covid-19, no podemos volver al sello y el papel"},"content":{"rendered":"<p><strong>Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Julio 2 de 2020.<\/strong><\/p>\n<p><strong>Despu\u00e9s del covid-19, no podemos volver al sello y el papel<\/strong><\/p>\n<p>Cuando contemos lo bueno que nos dej\u00f3 esta crisis sanitaria, el paso a la digitalizaci\u00f3n de la justicia deber\u00eda estar dentro de uno de ellos. Fue necesaria una pandemia para que finalmente di\u00e9ramos el gran paso de digitalizar la justicia.<\/p>\n<p><strong>\u00bfC\u00f3mo ha sido el proceso?<\/strong><br \/>\nDesde 2011 con la expedici\u00f3n del c\u00f3digo de procedimiento administrativo y de lo contencioso administrativo y luego en 2012 con el c\u00f3digo general del proceso, el uso de las tecnolog\u00edas de las comunicaciones dentro de los procedimientos administrativos y judiciales estaba establecido como una posibilidad supeditada a la implementaci\u00f3n de la tecnolog\u00eda que soportara el intercambio de informaci\u00f3n dentro del flujo de datos que supone una actuaci\u00f3n legal. Ha habido casos exitosos de virtualizaci\u00f3n como en los procesos arbitrales, las superintendencias que como la de Industria y Comercio, de Sociedades y Financiera han dispuesto de canales para la presentaci\u00f3n de demandas y memoriales v\u00eda electr\u00f3nica o la implementaci\u00f3n de las notificaciones por este mismo medio, pero, no hab\u00eda sido posible que el grueso de Rama Judicial adecuara sus actuaciones a la tecnolog\u00eda, de ah\u00ed que, la regla general segu\u00eda siendo el papel y el sello.<\/p>\n<p>Ten\u00edamos tenues avances en la publicaci\u00f3n de estados y traslados en l\u00ednea, as\u00ed como alg\u00fan otro tr\u00e1mite menor, pero, la presentaci\u00f3n de las demandas con todos sus anexos, deb\u00eda radicarse en f\u00edsico y ante los tribunales o juzgados competentes y aunque se hab\u00eda eliminado la presentaci\u00f3n personal de documentos, a\u00fan hay operadores jur\u00eddicos que la exigen. La asistencia a las audiencias, con contadas excepciones, era necesariamente presencial, en sedes judiciales no muy bien preparadas para recibir a las partes y testigos.<\/p>\n<p>El distanciamiento social, la inexistencia de una vacuna confiable en el mediano plazo y la facilidad del contagio ha llevado a que el Gobierno Nacional hubiere decretado la implementaci\u00f3n \u201cde las tecnolog\u00edas de la informaci\u00f3n y las comunicaciones en las actuaciones judiciales\u201d, con el objeto de \u201cagilizar el tr\u00e1mite de los procesos judiciales\u201d y \u201cflexibilizar la atenci\u00f3n a los usuarios\u201d. El Decreto 806 del 4 de junio de 2020, convirti\u00f3 en regla general lo que era la excepci\u00f3n e impuso la obligaci\u00f3n de \u201cutilizar las tecnolog\u00edas de la informaci\u00f3n y de las comunicaciones en la gesti\u00f3n y tr\u00e1mite de los procesos judiciales y asuntos en curso, con el fin de agilizar el acceso a la justicia\u201d.<\/p>\n<p>En desarrollo de las anteriores finalidades, la direcci\u00f3n de correo electr\u00f3nico ser\u00e1 el canal de comunicaci\u00f3n entre el juez y las partes durante todo el proceso. En adelante, la demanda y sus anexos, debe ser presentada por medios virtuales a los canales que habilite el operador jur\u00eddico para el efecto, al mismo tiempo debe envi\u00e1rsele por la misma v\u00eda al futuro demandado, de tal manera que el juez si admite la demanda, solo tendr\u00e1 que notificar mediante correo electr\u00f3nico al demandado la admisi\u00f3n de la misma. Los poderes podr\u00e1n otorgarse a trav\u00e9s del correo electr\u00f3nico; respecto de las audiencias, estas deber\u00e1n realizarse por medios virtuales, los cuales pueden ser puestos a disposici\u00f3n del proceso por las partes, en caso de que el operador jur\u00eddico no tenga la posibilidad t\u00e9cnica de hacerlo, lo que es realmente un gran avance, entre otras medidas que permitir\u00e1n una pronta justicia. A partir del 1 de julio de 2020, se reanudar\u00e1n los t\u00e9rminos judiciales suspendidos y la reforma comenzar\u00eda a regir en la pr\u00e1ctica.<\/p>\n<p><strong>\u00bfQu\u00e9 implica que el decreto tenga una vigencia temporal?<\/strong><br \/>\nEsta circunstancia es el punto negro del decreto. Su vigencia se fij\u00f3 en dos a\u00f1os. Ser\u00eda realmente un retroceso imperdonable si en estos dos a\u00f1os no se tramitara una reforma a los c\u00f3digos existentes que permitan incorporar estas reformas y hacer la legislaci\u00f3n permanente.<\/p>\n<p><strong>*Puedes leer, tambi\u00e9n, esta columna de opini\u00f3n en el portal Asuntos Legales; <a href=\"https:\/\/www.asuntoslegales.com.co\/consultorio\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel-3025432\" target=\"_blank\" rel=\"noopener\">clic ac\u00e1<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Julio 2 de 2020. Despu\u00e9s&#8230;<\/p>","protected":false},"author":1,"featured_media":868,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15],"tags":[51],"class_list":["post-972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-la-republica","tag-asuntos-legales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Despu\u00e9s del covid-19, no podemos volver al sello y el papel - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despu\u00e9s del covid-19, no podemos volver al sello y el papel - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Julio 2 de 2020. Despu\u00e9s...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T20:56:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T05:54:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"304\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"Despu\u00e9s del covid-19, no podemos volver al sello y el papel\",\"datePublished\":\"2020-07-02T20:56:19+00:00\",\"dateModified\":\"2022-05-27T05:54:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/\"},\"wordCount\":727,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"keywords\":[\"Asuntos Legales\"],\"articleSection\":[\"Diario La Rep\u00fablica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/\",\"name\":\"Despu\u00e9s del covid-19, no podemos volver al sello y el papel - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"datePublished\":\"2020-07-02T20:56:19+00:00\",\"dateModified\":\"2022-05-27T05:54:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/dionisio_240.jpg\",\"width\":240,\"height\":304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/07\\\/02\\\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Despu\u00e9s del covid-19, no podemos volver al sello y el papel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Despu\u00e9s del covid-19, no podemos volver al sello y el papel - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/","og_locale":"en_US","og_type":"article","og_title":"Despu\u00e9s del covid-19, no podemos volver al sello y el papel - Archila Abogados","og_description":"Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Julio 2 de 2020. Despu\u00e9s...","og_url":"https:\/\/archilaabogados.com\/en\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/","og_site_name":"Archila Abogados","article_published_time":"2020-07-02T20:56:19+00:00","article_modified_time":"2022-05-27T05:54:17+00:00","og_image":[{"width":240,"height":304,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"Despu\u00e9s del covid-19, no podemos volver al sello y el papel","datePublished":"2020-07-02T20:56:19+00:00","dateModified":"2022-05-27T05:54:17+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/"},"wordCount":727,"image":{"@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","keywords":["Asuntos Legales"],"articleSection":["Diario La Rep\u00fablica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/","url":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/","name":"Despu\u00e9s del covid-19, no podemos volver al sello y el papel - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","datePublished":"2020-07-02T20:56:19+00:00","dateModified":"2022-05-27T05:54:17+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2020\/04\/dionisio_240.jpg","width":240,"height":304},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2020\/07\/02\/despues-del-covid-19-no-podemos-volver-al-sello-y-el-papel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"Despu\u00e9s del covid-19, no podemos volver al sello y el papel"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=972"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/972\/revisions"}],"predecessor-version":[{"id":1556,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/972\/revisions\/1556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/868"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}