{"id":975,"date":"2020-06-04T12:56:34","date_gmt":"2020-06-04T12:56:34","guid":{"rendered":"https:\/\/archilaabogados.com\/?p=2753"},"modified":"2022-05-27T05:54:17","modified_gmt":"2022-05-27T05:54:17","slug":"la-recoleccion-de-datos-en-especial-los-datos-sensibles","status":"publish","type":"post","link":"https:\/\/archilaabogados.com\/en\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/","title":{"rendered":"La recolecci\u00f3n de datos, en especial, los datos sensibles"},"content":{"rendered":"<p><strong>Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Junio 4 de 2020.<\/strong><\/p>\n<p>Otra de las necesidades surgidas por la aparici\u00f3n del covid-19, tiene que ver con el seguimiento a la propagaci\u00f3n del virus a partir de los ciudadanos portadores y las personas a las que hubiere podido contagiar. Para esto, siguiendo las experiencias exitosas, a la luz de los resultados, de Corea del Sur, Hong Kong y China se han dise\u00f1ado aplicaciones manejadas por los entes territoriales para hacer seguimiento a la ciudadan\u00eda, previa la entrega de datos personales sensibles, que en tiempos normales ser\u00eda impensable. El \u00faltimo intento de implementaci\u00f3n de este esquema es el de la Alcald\u00eda de Bogot\u00e1 a trav\u00e9s de la aplicaci\u00f3n \u201cGabo\u201d y la plataforma www.bogota.gov.co\/bogota-cuidadora, donde la informaci\u00f3n \u201crecabada ser\u00e1 usada para prevenir, por ejemplo, la aglomeraci\u00f3n de personas en puntos de la ciudad, ajustar la oferta de servicios distritales como el transporte p\u00fablico, regular el flujo de personas en lugares y, en general, cuidarnos frente a situaciones espec\u00edficas que puedan convertirse en focos de alto riesgo de contagio\u201d.<\/p>\n<p><strong>\u00bfEs obligatorio, como se desprende de los decretos emanados de la Alcald\u00eda de Bogot\u00e1, la entrega de datos personales por parte de sus titulares?<\/strong><br \/>\nNo es obligatorio la entrega de datos personales por parte de la ciudadan\u00eda. Si bien en el decreto distrital 131 de 2020 se impuso la obligatoriedad a todos los ciudadanos que estuvieren en alguna de las actividades exceptuadas del aislamiento preventivo obligatorio, de inscribirse en la p\u00e1gina habilitada por el Distrito y entregar sus datos personales, la Alcaldesa inmediatamente derog\u00f3 parcial y verbalmente el decreto, y aclar\u00f3 que no exist\u00eda tal obligaci\u00f3n ya que la inscripci\u00f3n era voluntaria. Tal aclaraci\u00f3n se debe a que la ley de protecci\u00f3n de datos personales (ley 1581 de 2012 y el decreto 1377 de 2013), establece que para la recolecci\u00f3n de cualquier dato personal, que es toda aquella informaci\u00f3n que permita ligar o asociar a una persona al mismo, es necesaria la autorizaci\u00f3n previa, expresa e informada de su titular. Esto implica que el titular del dato, esto es, usted o yo se\u00f1or lector, debe autorizar, sin presiones, si quiere o no entregar sus datos personales, cosa que parece muy poco probable cuando a los ciudadanos nos imponen por decreto tener que entregar datos so pena de arriesgarse a una sanci\u00f3n, as\u00ed sea pedag\u00f3gica, si las autoridades lo sorprenden en actividades tan b\u00e1sicas como adquirir alimentos.<\/p>\n<p><strong>\u00bfSi los datos que se exigen son relacionados con la salud, tiene alguna protecci\u00f3n adicional?<\/strong><br \/>\nS\u00ed. Estos datos pertenecen a una categor\u00eda especial de datos llamados \u201cdatos sensibles\u201d, que son aquellos datos que afectan la intimidad del titular y cuyo uso indebido puede generar discriminaci\u00f3n, como los que revelen del titular del dato su origen \u00e9tnico o racial, su inclinaci\u00f3n pol\u00edtica o convicciones religiosas, su pertenencia a sindicatos u organizaciones sociales o de derechos humanos, as\u00ed como los datos relativos a la salud, a la vida sexual o los datos biom\u00e9tricos. Estos datos tienen una especial protecci\u00f3n: (i) es prohibido su tratamiento, la autorizaci\u00f3n debe ser \u201cexpl\u00edcita\u201d del titular; (ii) el titular del dato sensible no se encuentra obligado a \u201cautorizar su tratamiento\u201d, y (ii) ninguna actividad puede estar condicionada a la entrega del mismo.<\/p>\n<p>Entonces, no ten\u00eda otra posibilidad el Distrito que aclarar que no era obligatorio el suministro de los datos relacionados con la salud. No deja de ser un tema muy pol\u00e9mico, pero el equilibrio entre la salud p\u00fablica y la intimidad debe ser tratado en una escenario m\u00e1s amplio y sin tantas premuras, para un adecuado equilibrio de ambos derechos.<\/p>\n<p><strong>Puedes leer el texto original del portal Asuntos Legales, dando <a href=\"https:\/\/www.asuntoslegales.com.co\/consultorio\/la-recoleccion-de-datos-en-especial-los-datos-sensibles-3013578\" target=\"_blank\" rel=\"noopener\">clic ac\u00e1.<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Junio 4 de 2020. Otra&#8230;<\/p>","protected":false},"author":1,"featured_media":885,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[15],"tags":[51],"class_list":["post-975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diario-la-republica","tag-asuntos-legales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La recolecci\u00f3n de datos, en especial, los datos sensibles - Archila Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/archilaabogados.com\/en\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La recolecci\u00f3n de datos, en especial, los datos sensibles - Archila Abogados\" \/>\n<meta property=\"og:description\" content=\"Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Junio 4 de 2020. Otra...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archilaabogados.com\/en\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/\" \/>\n<meta property=\"og:site_name\" content=\"Archila Abogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-04T12:56:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T05:54:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/05\/dionisio240_temario.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ArhilAdmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ArhilAdmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/\"},\"author\":{\"name\":\"ArhilAdmin\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"headline\":\"La recolecci\u00f3n de datos, en especial, los datos sensibles\",\"datePublished\":\"2020-06-04T12:56:34+00:00\",\"dateModified\":\"2022-05-27T05:54:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/\"},\"wordCount\":662,\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/dionisio240_temario.jpg\",\"keywords\":[\"Asuntos Legales\"],\"articleSection\":[\"Diario La Rep\u00fablica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/\",\"name\":\"La recolecci\u00f3n de datos, en especial, los datos sensibles - Archila Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/dionisio240_temario.jpg\",\"datePublished\":\"2020-06-04T12:56:34+00:00\",\"dateModified\":\"2022-05-27T05:54:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/dionisio240_temario.jpg\",\"contentUrl\":\"https:\\\/\\\/archilaabogados.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/dionisio240_temario.jpg\",\"width\":240,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/2020\\\/06\\\/04\\\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/archilaabogados.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La recolecci\u00f3n de datos, en especial, los datos sensibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#website\",\"url\":\"https:\\\/\\\/archilaabogados.com\\\/\",\"name\":\"Archila Abogados\",\"description\":\"Servicios legales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archilaabogados.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/archilaabogados.com\\\/#\\\/schema\\\/person\\\/2ebc59f80cf35317c2a9f16341ee7883\",\"name\":\"ArhilAdmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g\",\"caption\":\"ArhilAdmin\"},\"sameAs\":[\"https:\\\/\\\/archilaabogados.com\"],\"url\":\"https:\\\/\\\/archilaabogados.com\\\/en\\\/author\\\/arhiladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La recolecci\u00f3n de datos, en especial, los datos sensibles - Archila Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/archilaabogados.com\/en\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/","og_locale":"en_US","og_type":"article","og_title":"La recolecci\u00f3n de datos, en especial, los datos sensibles - Archila Abogados","og_description":"Columna de opini\u00f3n del Dr. Dionisio de la Cruz para el portal Asuntos Legales. Junio 4 de 2020. Otra...","og_url":"https:\/\/archilaabogados.com\/en\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/","og_site_name":"Archila Abogados","article_published_time":"2020-06-04T12:56:34+00:00","article_modified_time":"2022-05-27T05:54:17+00:00","og_image":[{"width":240,"height":290,"url":"http:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/05\/dionisio240_temario.jpg","type":"image\/jpeg"}],"author":"ArhilAdmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ArhilAdmin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/#article","isPartOf":{"@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/"},"author":{"name":"ArhilAdmin","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"headline":"La recolecci\u00f3n de datos, en especial, los datos sensibles","datePublished":"2020-06-04T12:56:34+00:00","dateModified":"2022-05-27T05:54:17+00:00","mainEntityOfPage":{"@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/"},"wordCount":662,"image":{"@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/05\/dionisio240_temario.jpg","keywords":["Asuntos Legales"],"articleSection":["Diario La Rep\u00fablica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/","url":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/","name":"La recolecci\u00f3n de datos, en especial, los datos sensibles - Archila Abogados","isPartOf":{"@id":"https:\/\/archilaabogados.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/#primaryimage"},"image":{"@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/#primaryimage"},"thumbnailUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/05\/dionisio240_temario.jpg","datePublished":"2020-06-04T12:56:34+00:00","dateModified":"2022-05-27T05:54:17+00:00","author":{"@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883"},"breadcrumb":{"@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/#primaryimage","url":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/05\/dionisio240_temario.jpg","contentUrl":"https:\/\/archilaabogados.com\/wp-content\/uploads\/2019\/05\/dionisio240_temario.jpg","width":240,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/archilaabogados.com\/2020\/06\/04\/la-recoleccion-de-datos-en-especial-los-datos-sensibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/archilaabogados.com\/"},{"@type":"ListItem","position":2,"name":"La recolecci\u00f3n de datos, en especial, los datos sensibles"}]},{"@type":"WebSite","@id":"https:\/\/archilaabogados.com\/#website","url":"https:\/\/archilaabogados.com\/","name":"Archila Abogados","description":"Servicios legales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archilaabogados.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/archilaabogados.com\/#\/schema\/person\/2ebc59f80cf35317c2a9f16341ee7883","name":"ArhilAdmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9dcaf3f4e6ece3ae0c14ad443b5883bafd050ab345f218cf32465ef4c68ec5f4?s=96&d=mm&r=g","caption":"ArhilAdmin"},"sameAs":["https:\/\/archilaabogados.com"],"url":"https:\/\/archilaabogados.com\/en\/author\/arhiladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/comments?post=975"}],"version-history":[{"count":1,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/975\/revisions"}],"predecessor-version":[{"id":1558,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/posts\/975\/revisions\/1558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media\/885"}],"wp:attachment":[{"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/media?parent=975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/categories?post=975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archilaabogados.com\/en\/wp-json\/wp\/v2\/tags?post=975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}